{"id":15098,"date":"2019-11-05T15:34:22","date_gmt":"2019-11-05T15:34:22","guid":{"rendered":"https:\/\/science.f4studio.de\/?p=15098"},"modified":"2023-08-23T16:11:21","modified_gmt":"2023-08-23T16:11:21","slug":"hlrn-iv-feierliche-einweihung-dezember-2019","status":"publish","type":"post","link":"https:\/\/science.f4studio.de\/en\/hlrn-iv-feierliche-einweihung-dezember-2019\/","title":{"rendered":"HLRN-IV, Feierliche Einweihung, Dezember 2019"},"content":{"rendered":"<h2>Feierliche Einweihung HLRN-IV Supercomputer<\/h2>\n<p>Wir freuen uns auf die feierliche Einweihung des HLRN-IV-Supercomputers im Dezember 2019. Bereits seit dem Jahr 2001 unterst\u00fctzt der Norddeutsche Verbund f\u00fcr Hoch- und H\u00f6chstleistungsrechnen (HLRN-Verbund) mit Rechenkapazit\u00e4ten die Spitzenforschung in Deutschland. Das System der vierten Generation hat knapp eine Viertelmillion Rechenkerne und ist etwa sechsmal so schnell wie das vorherige System.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir freuen uns auf die feierliche Einweihung des HLRN-IV-Supercomputers im Dezember 2019.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-15098","post","type-post","status-publish","format-standard","hentry","category-latest-news"],"_links":{"self":[{"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/posts\/15098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/comments?post=15098"}],"version-history":[{"count":1,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/posts\/15098\/revisions"}],"predecessor-version":[{"id":15099,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/posts\/15098\/revisions\/15099"}],"wp:attachment":[{"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/media?parent=15098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/categories?post=15098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/science.f4studio.de\/en\/wp-json\/wp\/v2\/tags?post=15098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}